{"id":1104,"date":"2019-06-19T19:12:05","date_gmt":"2019-06-19T19:12:05","guid":{"rendered":"http:\/\/www.hgsempai.fr\/carto\/?p=1104"},"modified":"2019-06-19T19:12:06","modified_gmt":"2019-06-19T19:12:06","slug":"des-disparites-de-developpement-en-afrique-australe","status":"publish","type":"post","link":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/","title":{"rendered":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"565\" height=\"482\" src=\"https:\/\/www.hgsempai.fr\/carto\/wp-content\/uploads\/2019\/06\/afrik_australe_idh.png\" alt=\"\" class=\"wp-image-1105\" srcset=\"https:\/\/www.hgsempai.fr\/carto\/wp-content\/uploads\/2019\/06\/afrik_australe_idh.png 565w, https:\/\/www.hgsempai.fr\/carto\/wp-content\/uploads\/2019\/06\/afrik_australe_idh-300x256.png 300w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[117,29,497,30,25],"class_list":["post-1104","post","type-post","status-publish","format-standard","hentry","category-geographie","tag-117","tag-afrique","tag-australe","tag-contemporaine","tag-idh"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"_hg_sempai_\"\/>\n\t<meta name=\"google-site-verification\" content=\"Ct4JKJDgDVvg1xaipn4sqVzT59LYWvx-48_6eLrX7zM\" \/>\n\t<meta name=\"keywords\" content=\"idh,afrique,australe,2014,contemporaine\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"L&#039;atelier carto d&#039;HG Sempai | Un site utilisant WordPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Idh en Afrique Australe (2014) | L&#039;atelier carto d&#039;HG Sempai\" \/>\n\t\t<meta property=\"og:description\" content=\"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-06-19T19:12:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-06-19T19:12:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Idh en Afrique Australe (2014) | L&#039;atelier carto d&#039;HG Sempai\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#article\",\"name\":\"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai\",\"headline\":\"Des disparit\\u00e9s de d\\u00e9veloppement en Afrique australe\",\"author\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/author\\\/_hg_sempai_\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/afrik_australe_idh.png\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#articleImage\",\"width\":565,\"height\":482},\"datePublished\":\"2019-06-19T19:12:05+00:00\",\"dateModified\":\"2019-06-19T19:12:06+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#webpage\"},\"articleSection\":\"G\\u00e9ographie, 2014, afrique, australe, contemporaine, idh\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/category\\\/geographie\\\/#listItem\",\"name\":\"G\\u00e9ographie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/category\\\/geographie\\\/#listItem\",\"position\":2,\"name\":\"G\\u00e9ographie\",\"item\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/category\\\/geographie\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#listItem\",\"name\":\"Des disparit\\u00e9s de d\\u00e9veloppement en Afrique australe\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#listItem\",\"position\":3,\"name\":\"Des disparit\\u00e9s de d\\u00e9veloppement en Afrique australe\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/category\\\/geographie\\\/#listItem\",\"name\":\"G\\u00e9ographie\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/#person\",\"name\":\"_hg_sempai_\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb67b141b30cefa9652db38ac3b6923932f07db0323594978fb05aaffd9f8261?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"_hg_sempai_\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/author\\\/_hg_sempai_\\\/#author\",\"url\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/author\\\/_hg_sempai_\\\/\",\"name\":\"_hg_sempai_\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb67b141b30cefa9652db38ac3b6923932f07db0323594978fb05aaffd9f8261?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"_hg_sempai_\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#webpage\",\"url\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/\",\"name\":\"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai\",\"description\":\"Des disparit\\u00e9s de d\\u00e9veloppement en Afrique australe\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/2019\\\/06\\\/19\\\/des-disparites-de-developpement-en-afrique-australe\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/author\\\/_hg_sempai_\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/author\\\/_hg_sempai_\\\/#author\"},\"datePublished\":\"2019-06-19T19:12:05+00:00\",\"dateModified\":\"2019-06-19T19:12:06+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/#website\",\"url\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/\",\"name\":\"L'atelier carto d'HG Sempai\",\"description\":\"Un site utilisant WordPress\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgsempai.fr\\\/carto\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai","description":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","canonical_url":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/","robots":"max-image-preview:large","keywords":"idh,afrique,australe,2014,contemporaine","webmasterTools":{"google-site-verification":"Ct4JKJDgDVvg1xaipn4sqVzT59LYWvx-48_6eLrX7zM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#article","name":"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai","headline":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","author":{"@id":"https:\/\/www.hgsempai.fr\/carto\/author\/_hg_sempai_\/#author"},"publisher":{"@id":"https:\/\/www.hgsempai.fr\/carto\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.hgsempai.fr\/carto\/wp-content\/uploads\/2019\/06\/afrik_australe_idh.png","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#articleImage","width":565,"height":482},"datePublished":"2019-06-19T19:12:05+00:00","dateModified":"2019-06-19T19:12:06+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#webpage"},"isPartOf":{"@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#webpage"},"articleSection":"G\u00e9ographie, 2014, afrique, australe, contemporaine, idh"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto#listItem","position":1,"name":"Accueil","item":"https:\/\/www.hgsempai.fr\/carto","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/#listItem","name":"G\u00e9ographie"}},{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/#listItem","position":2,"name":"G\u00e9ographie","item":"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#listItem","name":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#listItem","position":3,"name":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","previousItem":{"@type":"ListItem","@id":"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/#listItem","name":"G\u00e9ographie"}}]},{"@type":"Person","@id":"https:\/\/www.hgsempai.fr\/carto\/#person","name":"_hg_sempai_","image":{"@type":"ImageObject","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/fb67b141b30cefa9652db38ac3b6923932f07db0323594978fb05aaffd9f8261?s=96&d=mm&r=g","width":96,"height":96,"caption":"_hg_sempai_"}},{"@type":"Person","@id":"https:\/\/www.hgsempai.fr\/carto\/author\/_hg_sempai_\/#author","url":"https:\/\/www.hgsempai.fr\/carto\/author\/_hg_sempai_\/","name":"_hg_sempai_","image":{"@type":"ImageObject","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fb67b141b30cefa9652db38ac3b6923932f07db0323594978fb05aaffd9f8261?s=96&d=mm&r=g","width":96,"height":96,"caption":"_hg_sempai_"}},{"@type":"WebPage","@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#webpage","url":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/","name":"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai","description":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.hgsempai.fr\/carto\/#website"},"breadcrumb":{"@id":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/#breadcrumblist"},"author":{"@id":"https:\/\/www.hgsempai.fr\/carto\/author\/_hg_sempai_\/#author"},"creator":{"@id":"https:\/\/www.hgsempai.fr\/carto\/author\/_hg_sempai_\/#author"},"datePublished":"2019-06-19T19:12:05+00:00","dateModified":"2019-06-19T19:12:06+00:00"},{"@type":"WebSite","@id":"https:\/\/www.hgsempai.fr\/carto\/#website","url":"https:\/\/www.hgsempai.fr\/carto\/","name":"L'atelier carto d'HG Sempai","description":"Un site utilisant WordPress","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.hgsempai.fr\/carto\/#person"}}]},"og:locale":"fr_FR","og:site_name":"L'atelier carto d'HG Sempai | Un site utilisant WordPress","og:type":"article","og:title":"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai","og:description":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","og:url":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/","article:published_time":"2019-06-19T19:12:05+00:00","article:modified_time":"2019-06-19T19:12:06+00:00","twitter:card":"summary","twitter:title":"Idh en Afrique Australe (2014) | L'atelier carto d'HG Sempai","twitter:description":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe"},"aioseo_meta_data":{"post_id":"1104","title":"Idh en Afrique Australe (2014) | #site_title","description":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","keywords":[{"label":"IDH","value":"IDH"},{"label":"idh","value":"idh"},{"label":"Afrique","value":"Afrique"},{"label":"australe","value":"australe"},{"label":"2014","value":"2014"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-22 09:24:02","updated":"2025-06-04 00:42:45","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hgsempai.fr\/carto\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/\" title=\"G\u00e9ographie\">G\u00e9ographie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDes disparit\u00e9s de d\u00e9veloppement en Afrique australe\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/www.hgsempai.fr\/carto"},{"label":"G\u00e9ographie","link":"https:\/\/www.hgsempai.fr\/carto\/category\/geographie\/"},{"label":"Des disparit\u00e9s de d\u00e9veloppement en Afrique australe","link":"https:\/\/www.hgsempai.fr\/carto\/2019\/06\/19\/des-disparites-de-developpement-en-afrique-australe\/"}],"_links":{"self":[{"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/posts\/1104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/comments?post=1104"}],"version-history":[{"count":1,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/posts\/1104\/revisions"}],"predecessor-version":[{"id":1106,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/posts\/1104\/revisions\/1106"}],"wp:attachment":[{"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/media?parent=1104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/categories?post=1104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hgsempai.fr\/carto\/wp-json\/wp\/v2\/tags?post=1104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}